{"id":8013,"date":"2023-09-19T14:24:06","date_gmt":"2023-09-19T07:24:06","guid":{"rendered":"https:\/\/www.tistr.or.th\/PressCenter\/?p=8013"},"modified":"2023-09-19T14:51:11","modified_gmt":"2023-09-19T07:51:11","slug":"%e0%b8%a3%e0%b8%a1%e0%b8%a7-%e0%b8%ad%e0%b8%a7-%e0%b9%81%e0%b8%96%e0%b8%a5%e0%b8%87%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%82%e0%b8%b1%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a5","status":"publish","type":"post","link":"https:\/\/www.tistr.or.th\/PressCenter\/news\/8013\/","title":{"rendered":"\u0e23\u0e21\u0e27. \u0e2d\u0e27. \u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07 \u0e2d\u0e27. \u0e0a\u0e39 \u201c\u0e40\u0e23\u0e35\u0e22\u0e19\u0e14\u0e35 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02 \u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21 \u201c\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e35 \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c \u0e15\u0e23\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u201d"},"content":{"rendered":"\n<p>\u0e19.\u0e2a.\u0e28\u0e38\u0e20\u0e21\u0e32\u0e2a \u0e2d\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.) \u0e21\u0e2d\u0e1a\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07 \u0e2d\u0e27. \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49 \u0e14\u0e23.\u0e0a\u0e38\u0e15\u0e34\u0e21\u0e32 \u0e40\u0e2d\u0e35\u0e48\u0e22\u0e21\u0e42\u0e0a\u0e15\u0e34\u0e0a\u0e27\u0e25\u0e34\u0e15 \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e27\u0e27.) \u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 19 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2566 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27\u0e0a\u0e31\u0e49\u0e19 1 \u0e2a\u0e1b.\u0e2d\u0e27.<br>\u0e23\u0e21\u0e27.\u0e2d\u0e27. \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e41\u0e16\u0e25\u0e07\u0e15\u0e48\u0e2d\u0e23\u0e31\u0e10\u0e2a\u0e20\u0e32 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e21\u0e38\u0e48\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e21\u0e34\u0e15\u0e34\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e42\u0e14\u0e22\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e37\u0e2d \u201c\u0e40\u0e23\u0e35\u0e22\u0e19\u0e14\u0e35 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02 \u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u201d \u0e22\u0e36\u0e14\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07 \u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e37\u0e2d \u201c\u0e27\u0e34\u0e08\u0e31\u0e22-\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e35 \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c \u0e15\u0e23\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u201d \u0e41\u0e25\u0e30 &#8220;\u0e40\u0e19\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 Go Green, \u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07, \u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 (Sustainability), \u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e32\u0e07\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 (Carbon Neutrality) , \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14, \u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21, \u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e ,\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)&#8221; \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e2d\u0e27. \u0e22\u0e31\u0e07\u0e40\u0e19\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d &#8220;\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e19\u0e33 \u0e23\u0e31\u0e10\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19&#8221; \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e27\u0e48\u0e32\u0e04\u0e27\u0e23\u0e08\u0e30\u0e17\u0e33\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e30\u0e44\u0e23 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e41\u0e25\u0e49\u0e27\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e02\u0e2d\u0e07 \u0e2d\u0e27. \u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07 \u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e19\u0e33 (market-driven) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e25\u0e14\u0e25\u0e47\u0e2d\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a \u0e02\u0e49\u0e2d\u0e08\u0e33\u0e01\u0e31\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e08\u0e30\u0e21\u0e38\u0e48\u0e07\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e08\u0e33\u0e19\u0e27\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e15\u0e2d\u0e31\u0e1e SMEs \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"8014\" src=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_28-1024x683.jpg\" alt=\"\" class=\"wp-image-8014\" srcset=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_28-1024x683.jpg 1024w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_28-300x200.jpg 300w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_28-768x512.jpg 768w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_28-1536x1025.jpg 1536w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_28.jpg 1568w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"8015\" src=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_53-1024x683.jpg\" alt=\"\" class=\"wp-image-8015\" srcset=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_53-1024x683.jpg 1024w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_53-300x200.jpg 300w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_53-768x512.jpg 768w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_53-1536x1025.jpg 1536w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_53.jpg 1568w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_55-1024x683.jpg\" alt=\"\" class=\"wp-image-8017\" srcset=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_55-1024x683.jpg 1024w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_55-300x200.jpg 300w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_55-768x512.jpg 768w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_55-1536x1025.jpg 1536w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_55.jpg 1568w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_71-1024x683.jpg\" alt=\"\" class=\"wp-image-8020\" srcset=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_71-1024x683.jpg 1024w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_71-300x200.jpg 300w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_71-768x512.jpg 768w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_71-1536x1025.jpg 1536w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/LINE_ALBUM_\u0e41\u0e16\u0e25\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22_\u0e52\u0e53\u0e50\u0e59\u0e51\u0e59_71.jpg 1568w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"8023\" src=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109617730-1024x724.jpg\" alt=\"\" class=\"wp-image-8023\" srcset=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109617730-1024x724.jpg 1024w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109617730-300x212.jpg 300w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109617730-768x543.jpg 768w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109617730-700x496.jpg 700w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109617730.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"8024\" src=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109647718-1024x724.jpg\" alt=\"\" class=\"wp-image-8024\" srcset=\"https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109647718-1024x724.jpg 1024w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109647718-300x212.jpg 300w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109647718-768x543.jpg 768w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109647718-700x496.jpg 700w, https:\/\/www.tistr.or.th\/PressCenter\/wp-content\/uploads\/messageImage_1695109647718.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<p>Views: 166<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0e19.\u0e2a.\u0e28\u0e38\u0e20\u0e21\u0e32\u0e2a \u0e2d\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.) \u0e21\u0e2d\u0e1a\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07 \u0e2d\u0e27. \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49 \u0e14\u0e23.\u0e0a\u0e38\u0e15\u0e34\u0e21\u0e32 \u0e40\u0e2d\u0e35\u0e48\u0e22\u0e21\u0e42\u0e0a\u0e15\u0e34\u0e0a\u0e27\u0e25\u0e34\u0e15 \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e27\u0e34\u0e17&hellip; <\/p>\n","protected":false},"author":2,"featured_media":8019,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.tistr.or.th\/PressCenter\/wp-json\/wp\/v2\/posts\/8013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tistr.or.th\/PressCenter\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tistr.or.th\/PressCenter\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tistr.or.th\/PressCenter\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tistr.or.th\/PressCenter\/wp-json\/wp\/v2\/comments?post=8013"}],"version-history":[{"count":2,"href":"https:\/\/www.tistr.or.th\/PressCenter\/wp-json\/wp\/v2\/posts\/8013\/revisions"}],"predecessor-version":[{"id":8025,"href":"https:\/\/www.tistr.or.th\/PressCenter\/wp-json\/wp\/v2\/posts\/8013\/revisions\/8025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tistr.or.th\/PressCenter\/wp-json\/wp\/v2\/media\/8019"}],"wp:attachment":[{"href":"https:\/\/www.tistr.or.th\/PressCenter\/wp-json\/wp\/v2\/media?parent=8013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tistr.or.th\/PressCenter\/wp-json\/wp\/v2\/categories?post=8013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tistr.or.th\/PressCenter\/wp-json\/wp\/v2\/tags?post=8013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}